{"id":2717,"date":"2019-01-31T18:13:10","date_gmt":"2019-01-31T18:13:10","guid":{"rendered":"https:\/\/www.todsystem.com\/it\/?p=2717"},"modified":"2022-10-14T15:14:10","modified_gmt":"2022-10-14T14:14:10","slug":"presentazione-tod-system-al-talentlab","status":"publish","type":"post","link":"https:\/\/www.todsystem.com\/fr\/presentation-du-systeme-tod-au-talentlab\/","title":{"rendered":"Pr\u00e9sentation de la plateforme du syst\u00e8me TOD au Talent LAB"},"content":{"rendered":"<p>L'<strong>Plate-forme innovante du syst\u00e8me TOD<\/strong> a \u00e9t\u00e9 s\u00e9lectionn\u00e9 parmi les <strong>les meilleures id\u00e9es d'entreprise<\/strong> pour la participation au cours <strong>Laboratoire des talents<\/strong>. Cette initiative d\u00e9coule de l'\u00e9troite collaboration entre la r\u00e9gion de Calabre et CalabriaInnova et vise \u00e0 soutenir la cr\u00e9ation de micro-entreprises innovantes et de spin-offs de recherche par des dipl\u00f4m\u00e9s, des doctorants et\/ou des chercheurs. <\/p>\n\n\n\n<p><strong>Le syst\u00e8me TOD est plac\u00e9 sur la voie de l'excellence<\/strong> qui a vu la collaboration de consultants tels que l'incubateur I3P de l'\u00e9cole polytechnique de Turin et la soci\u00e9t\u00e9 multinationale PwC.<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La plateforme innovante TOD System a \u00e9t\u00e9 s\u00e9lectionn\u00e9e comme l'une des meilleures id\u00e9es d'entreprise pour participer au volet Talent Lab. Cette initiative est le r\u00e9sultat d'une \u00e9troite collaboration entre la r\u00e9gion de Calabre et CalabriaInnova et vise \u00e0 soutenir la cr\u00e9ation de micro-entreprises innovantes et de spin-offs de recherche par des dipl\u00f4m\u00e9s, des doctorants et\/ou des ... <a title=\"Pr\u00e9sentation de la plateforme du syst\u00e8me TOD au Talent LAB\" class=\"read-more\" href=\"https:\/\/www.todsystem.com\/fr\/presentation-du-systeme-tod-au-talentlab\/\" aria-label=\"En savoir plus sur Pr\u00e9sentation de la plateforme du syst\u00e8me TOD au Talent LAB\">Lire la suite<\/a><\/p>","protected":false},"author":1,"featured_media":12423,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70],"tags":[19,20,18],"class_list":["post-2717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie","tag-innovazione","tag-startup","tag-talent-lab"],"_links":{"self":[{"href":"https:\/\/www.todsystem.com\/fr\/wp-json\/wp\/v2\/posts\/2717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todsystem.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todsystem.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todsystem.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todsystem.com\/fr\/wp-json\/wp\/v2\/comments?post=2717"}],"version-history":[{"count":8,"href":"https:\/\/www.todsystem.com\/fr\/wp-json\/wp\/v2\/posts\/2717\/revisions"}],"predecessor-version":[{"id":9031,"href":"https:\/\/www.todsystem.com\/fr\/wp-json\/wp\/v2\/posts\/2717\/revisions\/9031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todsystem.com\/fr\/wp-json\/wp\/v2\/media\/12423"}],"wp:attachment":[{"href":"https:\/\/www.todsystem.com\/fr\/wp-json\/wp\/v2\/media?parent=2717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todsystem.com\/fr\/wp-json\/wp\/v2\/categories?post=2717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todsystem.com\/fr\/wp-json\/wp\/v2\/tags?post=2717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}