{"id":19454,"date":"2024-10-14T16:49:00","date_gmt":"2024-10-14T15:49:00","guid":{"rendered":"https:\/\/www.todsystem.com\/?p=19454"},"modified":"2025-07-22T10:53:01","modified_gmt":"2025-07-22T09:53:01","slug":"gitex-global-2024-innovazione-robotica-e-sostenibilita-nel-cuore-della-tecnologia-globale","status":"publish","type":"post","link":"https:\/\/www.todsystem.com\/fr\/gitex-global-2024-linnovation-robotique-et-la-durabilite-au-coeur-de-la-technologie-mondiale\/","title":{"rendered":"GITEX GLOBAL 2024 : Innovation, robotique et durabilit\u00e9 au c\u0153ur de la technologie mondiale"},"content":{"rendered":"<p>Du 14 au 18 octobre 2024, TOD System a particip\u00e9 \u00e0 GITEX GLOBAL, la plus grande exposition de technologies et de start-ups au monde, qui s'est tenue au Dubai World Trade Centre. Cet \u00e9v\u00e9nement a rassembl\u00e9 les plus grands innovateurs, les pionniers de la technologie et les leaders visionnaires de plus de 180 pays dans un \u00e9v\u00e9nement de cinq jours d'excellence technologique, avec des d\u00e9monstrations en direct, des lancements r\u00e9volutionnaires et des conf\u00e9rences qui fa\u00e7onneront l'avenir de l'industrie.<\/p>\n\n\n\n<p>Au cours de l'\u00e9v\u00e9nement, nous avons eu l'occasion de pr\u00e9senter nos solutions et d'entrer en contact avec un r\u00e9seau mondial de professionnels. Nous \u00e9tions pr\u00e9sents sur le stand de l'ITA - Italian Trade Agency - \u00e0 l'\u00e9tape 8 du port de Duba\u00ef, o\u00f9 nous avons discut\u00e9 avec les visiteurs et les partenaires potentiels de la mani\u00e8re de transformer les investissements dans la robotique en v\u00e9ritables moteurs de rendement \u00e9conomique et d'innovation. <\/p>\n\n\n\n<p>Pour le Syst\u00e8me TOD, la participation \u00e0 des \u00e9v\u00e9nements de cette ampleur a \u00e9t\u00e9 une occasion pr\u00e9cieuse de renforcer son r\u00f4le dans l'\u00e9cosyst\u00e8me mondial de l'innovation, en promouvant des solutions technologiques de pointe pr\u00eates \u00e0 faire la diff\u00e9rence sur les march\u00e9s internationaux.<\/p>\n\n\n\n<p>Restez avec nous pour suivre les prochaines \u00e9tapes de notre voyage dans le monde de la robotique collaborative et de l'innovation technologique !<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-101.png\" alt=\"\" class=\"wp-image-19462\" srcset=\"https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-101.png 800w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-101-300x169.png 300w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-101-768x432.png 768w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-101-18x10.png 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-96-1024x768.png\" alt=\"\" class=\"wp-image-19456\" srcset=\"https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-96-1024x768.png 1024w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-96-300x225.png 300w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-96-768x576.png 768w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-96-1536x1152.png 1536w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-96-16x12.png 16w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-96.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-97-1024x768.png\" alt=\"\" class=\"wp-image-19457\" srcset=\"https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-97-1024x768.png 1024w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-97-300x225.png 300w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-97-768x576.png 768w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-97-1536x1152.png 1536w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-97-16x12.png 16w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-97.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-98-768x1024.png\" alt=\"\" class=\"wp-image-19458\" srcset=\"https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-98-768x1024.png 768w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-98-225x300.png 225w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-98-1152x1536.png 1152w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-98-9x12.png 9w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-98.png 1280w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-99-1024x768.png\" alt=\"\" class=\"wp-image-19459\" srcset=\"https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-99-1024x768.png 1024w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-99-300x225.png 300w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-99-768x576.png 768w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-99-1536x1152.png 1536w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-99-16x12.png 16w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-99.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-100-1024x576.png\" alt=\"\" class=\"wp-image-19460\" srcset=\"https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-100-1024x576.png 1024w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-100-300x169.png 300w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-100-768x432.png 768w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-100-1536x864.png 1536w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-100-18x10.png 18w, https:\/\/www.todsystem.com\/wp-content\/uploads\/2025\/07\/image-100.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>Dal 14 al 18 ottobre 2024, TOD System ha partecipato a GITEX GLOBAL, la pi\u00f9 grande fiera mondiale dedicata a tecnologia e startup, tenutasi presso il Dubai World Trade Centre. Questo evento ha visto riunirsi i maggiori innovatori, pionieri tecnologici e leader visionari provenienti da oltre 180 Paesi, in una cinque giorni di eccellenza tecnologica, &#8230; <a title=\"GITEX GLOBAL 2024 : Innovation, robotique et durabilit\u00e9 au c\u0153ur de la technologie mondiale\" class=\"read-more\" href=\"https:\/\/www.todsystem.com\/fr\/gitex-global-2024-linnovation-robotique-et-la-durabilite-au-coeur-de-la-technologie-mondiale\/\" aria-label=\"En savoir plus sur GITEX GLOBAL 2024: Innovazione, Robotica e Sostenibilit\u00e0 nel Cuore della Tecnologia Globale\">Lire la suite<\/a><\/p>","protected":false},"author":1,"featured_media":19488,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70],"tags":[],"class_list":["post-19454","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"_links":{"self":[{"href":"https:\/\/www.todsystem.com\/fr\/wp-json\/wp\/v2\/posts\/19454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todsystem.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todsystem.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todsystem.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todsystem.com\/fr\/wp-json\/wp\/v2\/comments?post=19454"}],"version-history":[{"count":3,"href":"https:\/\/www.todsystem.com\/fr\/wp-json\/wp\/v2\/posts\/19454\/revisions"}],"predecessor-version":[{"id":19489,"href":"https:\/\/www.todsystem.com\/fr\/wp-json\/wp\/v2\/posts\/19454\/revisions\/19489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todsystem.com\/fr\/wp-json\/wp\/v2\/media\/19488"}],"wp:attachment":[{"href":"https:\/\/www.todsystem.com\/fr\/wp-json\/wp\/v2\/media?parent=19454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todsystem.com\/fr\/wp-json\/wp\/v2\/categories?post=19454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todsystem.com\/fr\/wp-json\/wp\/v2\/tags?post=19454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}