{"id":19356,"date":"2025-06-11T14:12:00","date_gmt":"2025-06-11T13:12:00","guid":{"rendered":"https:\/\/www.todsystem.com\/?p=19356"},"modified":"2025-07-23T08:59:39","modified_gmt":"2025-07-23T07:59:39","slug":"i4sdg-2025-tecnologia-e-innovazione-per-un-futuro-sostenibile","status":"publish","type":"post","link":"https:\/\/www.todsystem.com\/es\/i4sdg-2025-tecnologia-e-innovacion-para-un-futuro-sostenible-2\/","title":{"rendered":"I4SDG 2025: Tecnolog\u00eda e innovaci\u00f3n para un futuro sostenible"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_79_2 counter-hierarchy ez-toc-counter ez-toc-transparent ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00edndice de contenido<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Palanca<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.todsystem.com\/es\/i4sdg-2025-tecnologia-e-innovacion-para-un-futuro-sostenible-2\/#Innovazione_e_Sostenibilita_in_scena_a_Villa_San_Giovanni\" >Innovaci\u00f3n y sostenibilidad a escena en Villa San Giovanni<\/a><\/li><\/ul><\/nav><\/div>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Innovazione_e_Sostenibilita_in_scena_a_Villa_San_Giovanni\"><\/span>Innovaci\u00f3n y sostenibilidad a escena en Villa San Giovanni<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>En <strong>Del 10 al 12 de junio de 2025<\/strong>la exitosa <strong>Tercera Conferencia Internacional de IFToMM para los Objetivos de Desarrollo Sostenible (I4SDG 2025)<\/strong>en el evocador marco del<strong>Altafiumara Resort &amp; Spa<\/strong> a <strong>Villa San Giovanni (RC)<\/strong>. Un acontecimiento de alcance internacional que logr\u00f3 combinar <strong>tecnolog\u00eda<\/strong>, <strong>sostenibilidad<\/strong> Y <strong>cooperaci\u00f3n mundial<\/strong>recordando m\u00e1s de <strong>200 delegados de 23 pa\u00edses<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Congreso internacional sobre innovaci\u00f3n sostenible<\/h3>\n\n\n\n<p>Promovido por la <strong>Prof. Giuseppe Carbone<\/strong> de la Universidad de Calabria, y patrocinado por <strong>IFToMM<\/strong>, <strong>DIMEG<\/strong>, <strong>Regi\u00f3n de Calabria<\/strong> y numerosas instituciones nacionales e internacionales, I4SDG 2025 represent\u00f3 un importante punto de encuentro entre <strong>investigadores<\/strong>, <strong>negocios<\/strong>, <strong>acad\u00e9micos<\/strong> Y <strong>responsables pol\u00edticos<\/strong> comprometida con el desarrollo de soluciones tecnol\u00f3gicas acordes con la <strong>Objetivos de Desarrollo Sostenible (ODS)<\/strong> de la Agenda 2030 de las Naciones Unidas.<\/p>\n\n\n\n<p>En la edici\u00f3n de 2025 <strong>lectio magistralis<\/strong>, <strong>sesiones t\u00e9cnicas paralelas<\/strong>talleres y presentaciones de proyectos sobre varios temas clave, entre ellos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\ud83c\udf31 <strong>Robots ecosostenibles<\/strong> (Proyecto PNRR FAIR)<\/li>\n\n\n\n<li>\ud83e\udd16 <strong>Exoesqueletos para rehabilitaci\u00f3n<\/strong> (Proyecto PNRR AGE-IT)<\/li>\n\n\n\n<li>\ud83c\udf4a <strong>Manipuladores blandos para la recogida de fruta<\/strong> (Proyecto PNRR Tech4YOU)<\/li>\n\n\n\n<li>\ud83c\udfdb <strong>Vigilancia de yacimientos arqueol\u00f3gicos costeros mediante drones<\/strong> (Proyecto PNRR Tech4YOU)<\/li>\n<\/ul>\n\n\n\n<p>Adem\u00e1s, el programa ofreci\u00f3 informaci\u00f3n sobre:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Inteligencia artificial <strong>conciencia ecol\u00f3gica<\/strong><\/li>\n\n\n\n<li>Interacci\u00f3n hombre-m\u00e1quina<\/li>\n\n\n\n<li>Agricultura inteligente y sostenible<\/li>\n\n\n\n<li>Rob\u00f3tica para una producci\u00f3n respetuosa con el medio ambiente<\/li>\n\n\n\n<li>Educaci\u00f3n innovadora en STEM<\/li>\n\n\n\n<li>Sistemas adaptables de almacenamiento de energ\u00eda<\/li>\n\n\n\n<li>Historia de las m\u00e1quinas y los mecanismos<\/li>\n<\/ul>\n\n\n\n<p>\ud83d\udcda Las actas de la conferencia se recogieron en dos vol\u00famenes publicados por <strong>Springer-Nature<\/strong>que atestiguan el rigor cient\u00edfico y el valor acad\u00e9mico de la iniciativa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La contribuci\u00f3n del TOD System: la tecnolog\u00eda se une a la sostenibilidad<\/h3>\n\n\n\n<p>En colaboraci\u00f3n con nuestro socio <strong>Fortek srl - Automatizaci\u00f3n y Suministros Industriales<\/strong>Tuvimos el honor de participar activamente en la conferencia, presentando nuestra <strong>TODROBOT TR1<\/strong>una soluci\u00f3n de vanguardia de <strong>rob\u00f3tica colaborativa m\u00f3vil<\/strong>.<\/p>\n\n\n\n<p>El <strong>TR1<\/strong> es un <strong>Robot manipulador m\u00f3vil aut\u00f3nomo (AMMR)<\/strong> dise\u00f1ados para trabajar en entornos din\u00e1micos y compartidos, capaces de adaptarse a diferentes contextos: desde el<strong>industria manufacturera<\/strong> a la<strong>cuidado personal<\/strong>hasta servicios avanzados. Nuestra demostraci\u00f3n mostr\u00f3 c\u00f3mo TR1 puede:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Optimizaci\u00f3n de los procesos de producci\u00f3n,<\/li>\n\n\n\n<li>Reducir los residuos y el consumo,<\/li>\n\n\n\n<li>Aumentar el <strong>seguridad<\/strong> Y <strong>eficacia<\/strong>,<\/li>\n\n\n\n<li>Mejorar la <strong>calidad del trabajo<\/strong> para el ser humano.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Una visi\u00f3n compartida y participativa<\/h3>\n\n\n\n<p>El inter\u00e9s mostrado por <strong>acad\u00e9micos<\/strong>, <strong>estudiantes<\/strong>, <strong>profesionales<\/strong> Y <strong>representantes de la industria<\/strong> confirm\u00f3 la centralidad del tema: c\u00f3mo <strong>rob\u00f3tica<\/strong> Y <strong>inteligencia artificial<\/strong> pueden desempe\u00f1ar un papel decisivo en la construcci\u00f3n de un futuro sostenible y centrado en el ser humano.<\/p>\n\n\n\n<p>Como subraya el <strong>Prof. Giuseppe Carbone<\/strong>:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\"Este evento es una oportunidad \u00fanica para tender puentes entre la investigaci\u00f3n y el tejido productivo, al tiempo que se valoriza el potencial sostenible del territorio calabr\u00e9s a escala internacional.\"<\/p>\n<\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\">Mirando al futuro<\/h3>\n\n\n\n<p>Estamos orgullosos de haber contribuido al \u00e9xito de <strong>I4SDG 2025<\/strong>un acontecimiento que demostr\u00f3 lo crucial que es la sinergia entre <strong>investigaci\u00f3n cient\u00edfica<\/strong>, <strong>innovaci\u00f3n tecnol\u00f3gica<\/strong> Y <strong>valorizaci\u00f3n del territorio<\/strong>. Nuestro compromiso contin\u00faa con energ\u00eda renovada para desarrollar soluciones cada vez m\u00e1s eficaces y responsables.<\/p>\n\n\n\n<p>\ud83c\udfa5 Para revivir algunos de los momentos m\u00e1s destacados del congreso, el reportaje emitido en <strong>LaC Noticias - Canal 11 TDT<\/strong>por periodista <strong>Silvio Cacciatore<\/strong>que supo transmitir con gran precisi\u00f3n la importancia y el impacto de las tecnolog\u00edas presentadas.<\/p>\n\n\n\n<p><strong>M\u00e1s informaci\u00f3n sobre TODROBOT TR1 y nuestras soluciones de automatizaci\u00f3n sostenible. P\u00f3ngase en contacto con nosotros para obtener m\u00e1s informaci\u00f3n o concertar una demostraci\u00f3n personalizada.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"TOD System en la Conferencia Internacional de IFToMM para los Objetivos de Desarrollo Sostenible (I4SDG 2025)\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/IHJsk9yHju8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>Innovazione e Sostenibilit\u00e0 in scena a Villa San Giovanni Dal 10 al 12 giugno 2025, si \u00e8 svolta con grande successo la terza edizione della International Conference of IFToMM for Sustainable Development Goals (I4SDG 2025), ospitata nella suggestiva cornice dell\u2019Altafiumara Resort &amp; Spa a Villa San Giovanni (RC). Un evento di portata internazionale che ha &#8230; <a title=\"I4SDG 2025: Tecnolog\u00eda e innovaci\u00f3n para un futuro sostenible\" class=\"read-more\" href=\"https:\/\/www.todsystem.com\/es\/i4sdg-2025-tecnologia-e-innovacion-para-un-futuro-sostenible-2\/\" aria-label=\"M\u00e1s en I4SDG 2025: Tecnolog\u00eda e innovaci\u00f3n para un futuro sostenible\">Leer m\u00e1s<\/a><\/p>","protected":false},"author":1,"featured_media":19508,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70],"tags":[],"class_list":["post-19356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"_links":{"self":[{"href":"https:\/\/www.todsystem.com\/es\/wp-json\/wp\/v2\/posts\/19356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todsystem.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todsystem.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todsystem.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todsystem.com\/es\/wp-json\/wp\/v2\/comments?post=19356"}],"version-history":[{"count":4,"href":"https:\/\/www.todsystem.com\/es\/wp-json\/wp\/v2\/posts\/19356\/revisions"}],"predecessor-version":[{"id":19523,"href":"https:\/\/www.todsystem.com\/es\/wp-json\/wp\/v2\/posts\/19356\/revisions\/19523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todsystem.com\/es\/wp-json\/wp\/v2\/media\/19508"}],"wp:attachment":[{"href":"https:\/\/www.todsystem.com\/es\/wp-json\/wp\/v2\/media?parent=19356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todsystem.com\/es\/wp-json\/wp\/v2\/categories?post=19356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todsystem.com\/es\/wp-json\/wp\/v2\/tags?post=19356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}